{"id":13599,"date":"2022-01-09T21:52:24","date_gmt":"2022-01-09T21:52:24","guid":{"rendered":"http:\/\/ahelth.com\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/"},"modified":"2022-01-11T01:34:19","modified_gmt":"2022-01-11T01:34:19","slug":"symptoms-of-excess-iodine-in-the-body-causes-and-treatment","status":"publish","type":"post","link":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/","title":{"rendered":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento."},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\">S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento.<\/span><\/span><\/span><\/span><\/p>\n<div>\n<p>&nbsp;<\/p>\n<p><noscript><img fetchpriority=\"high\" decoding=\"async\" loading=\"eager\" class=\"alignnone size-full first-post-img wp-image-223706\" src=\"https:\/\/static.dailymedicalinfo.com\/2018\/09\/\u0627\u0639\u0631\u0627\u0636-\u0632\u064a\u0627\u062f\u0629-\u0627\u0644\u064a\u0648\u062f-\u0641\u064a-\u0627\u0644\u062c\u0633\u0645.jpg\" alt=\"Symptoms of excess iodine in the body\" width=\"1200\" height=\"700\"\/><\/noscript><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El yodo est\u00e1 presente en el cuerpo en peque\u00f1as cantidades que el cuerpo necesita para producir hormonas tiroideas que regulan su crecimiento, as\u00ed como el metabolismo y otras funciones importantes. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Muchas fuentes de alimentos tambi\u00e9n contienen yodo, que el cuerpo debe absorber en ciertas cantidades. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Si el nivel de yodo en el cuerpo aumenta, \u00bfla condici\u00f3n se vuelve insalubre, es decir, qu\u00e9 tan alta es la ingesta diaria de yodo? <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00bfCu\u00e1les son los <\/span><\/span><\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">s\u00edntomas del exceso de yodo en el cuerpo<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> ? <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Esto es lo que vamos a averiguar en este art\u00edculo, querido lector, s\u00edguenos.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-1\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00bfCu\u00e1nto yodo necesita el cuerpo?<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La mayor\u00eda de los adultos deber\u00edan tratar de consumir alrededor de 150 microgramos de yodo por d\u00eda, por lo que aqu\u00ed hay una lista de los niveles m\u00e1ximos que una persona puede consumir por d\u00eda, medidos por diferentes grupos de edad:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ni\u00f1os de 1 a 3 a\u00f1os: 200 microgramos al d\u00eda.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ni\u00f1os de 4 a 8 a\u00f1os: 300 microgramos al d\u00eda.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Para ni\u00f1os de 9 a 13 a\u00f1os, 600 microgramos al d\u00eda.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Adolescentes 14-18 a\u00f1os, 900 mcg por d\u00eda.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Adultos de 19 a\u00f1os de edad y mayores, 1100 mcg por d\u00eda.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2 id=\"section-2\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">S\u00edntomas de exceso de yodo en el cuerpo.<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Si se absorbe m\u00e1s de la dosis diaria m\u00e1xima de yodo durante un largo per\u00edodo de tiempo, puede ocurrir intoxicaci\u00f3n por yodo, cuyos s\u00edntomas, seg\u00fan la cantidad de yodo en su cuerpo, var\u00edan de leves a graves:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">diarrea<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> ;<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">ardor en la boca;<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">n\u00e1usea;<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">v\u00f3mitos;<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Los s\u00edntomas graves de intoxicaci\u00f3n por yodo incluyen:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">hinchaz\u00f3n de las v\u00edas respiratorias;<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cambiar a color de piel azul.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">latido del coraz\u00f3n d\u00e9bil<\/span><\/span><\/span><\/span><\/li>\n<li><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">coma<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> .<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El consumo excesivo de yodo tambi\u00e9n puede conducir a una gl\u00e1ndula tiroides hiperactiva. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Los s\u00edntomas de la enfermedad son:<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-3\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00bfCu\u00e1l es la relaci\u00f3n entre los mariscos y el yodo?<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Contiene muchos tipos de <\/span><\/span><\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">mariscos<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> , incluidos camarones <\/span><\/span><\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">,<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> at\u00fan y <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">yodo: las algas tambi\u00e9n contienen niveles muy altos de yodo. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">En regiones y culturas que comen muchas algas y mariscos, las personas a veces consumen miles de microgramos de yodo en un solo d\u00eda.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Un estudio de 2001 estima que Jap\u00f3n consume una gran cantidad de yodo, principalmente de algas, y esto provoca este <\/span><\/span><\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">crecimiento excesivo<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> .Jap\u00f3n, pero a pesar de estos beneficios, se deben evitar las cantidades excesivas que pueden da\u00f1ar la salud.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-4\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Causas de la intoxicaci\u00f3n por yodo<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El envenenamiento por yodo generalmente es el resultado de tomar demasiados suplementos de yodo, ya que rara vez ocurre a partir de fuentes alimenticias.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El consumo de una sola dosis grande de yodo en los alimentos no suele provocar intoxicaci\u00f3n, pero el riesgo de infecci\u00f3n aumenta con el consumo continuado de grandes cantidades de yodo. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Algunos medicamentos tambi\u00e9n pueden aumentar la cantidad de yodo en el cuerpo &#8211; la frecuencia y el ritmo de los latidos del coraz\u00f3n Cada tableta contiene 75 mililitros de yodo, que es cientos de veces la cantidad diaria recomendada. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Los suplementos de yodo y potasio y las tomograf\u00edas computarizadas tambi\u00e9n contienen yodo.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-5\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Tratamiento del exceso de yodo en el cuerpo<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">El tratamiento de la intoxicaci\u00f3n por yodo generalmente requiere hospitalizaci\u00f3n y, dependiendo de la gravedad de sus s\u00edntomas, su m\u00e9dico puede recetarle antiem\u00e9ticos o tabletas de carb\u00f3n para ayudar a su cuerpo a prevenir la absorci\u00f3n de yodo.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Los s\u00edntomas m\u00e1s graves, como falta de aliento y dificultad para respirar, pueden requerir el uso de un ventilador hasta que los niveles de yodo disminuyan.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Y ahora, querido lector, despu\u00e9s de conocer los s\u00edntomas del exceso de yodo en el organismo, o lo que se conoce como intoxicaci\u00f3n por yodo,<\/span><\/span><\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. &nbsp; El yodo est\u00e1 presente en el cuerpo en peque\u00f1as cantidades que el cuerpo necesita para producir hormonas tiroideas que regulan su crecimiento, as\u00ed como el metabolismo y otras funciones importantes. Muchas fuentes de alimentos tambi\u00e9n contienen yodo, que el cuerpo debe absorber &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,28],"tags":[],"class_list":["post-13599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health\" \/>\n<meta property=\"og:description\" content=\"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. &nbsp; El yodo est\u00e1 presente en el cuerpo en peque\u00f1as cantidades que el cuerpo necesita para producir hormonas tiroideas que regulan su crecimiento, as\u00ed como el metabolismo y otras funciones importantes. Muchas fuentes de alimentos tambi\u00e9n contienen yodo, que el cuerpo debe absorber &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/\" \/>\n<meta property=\"og:site_name\" content=\"the health\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-09T21:52:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-11T01:34:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"headline\":\"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento.\",\"datePublished\":\"2022-01-09T21:52:24+00:00\",\"dateModified\":\"2022-01-11T01:34:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/\"},\"wordCount\":672,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/breakfast-g05e20e13e_640.jpg\",\"articleSection\":[\"Sin categorizar\",\"Sin categorizar\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/\",\"url\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/\",\"name\":\"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/breakfast-g05e20e13e_640.jpg\",\"datePublished\":\"2022-01-09T21:52:24+00:00\",\"dateModified\":\"2022-01-11T01:34:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/breakfast-g05e20e13e_640.jpg\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/breakfast-g05e20e13e_640.jpg\",\"width\":640,\"height\":426,\"caption\":\"Symptoms of excess iodine in the body, causes and treatment\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ahelth.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ahelth.com\\\/es\\\/\",\"name\":\"the health\",\"description\":\"Articles on health\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ahelth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/ahelth.com\"],\"url\":\"https:\\\/\\\/ahelth.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health","og_description":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. &nbsp; El yodo est\u00e1 presente en el cuerpo en peque\u00f1as cantidades que el cuerpo necesita para producir hormonas tiroideas que regulan su crecimiento, as\u00ed como el metabolismo y otras funciones importantes. Muchas fuentes de alimentos tambi\u00e9n contienen yodo, que el cuerpo debe absorber &hellip;","og_url":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/","og_site_name":"the health","article_published_time":"2022-01-09T21:52:24+00:00","article_modified_time":"2022-01-11T01:34:19+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#article","isPartOf":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/"},"author":{"name":"admin","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"headline":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento.","datePublished":"2022-01-09T21:52:24+00:00","dateModified":"2022-01-11T01:34:19+00:00","mainEntityOfPage":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/"},"wordCount":672,"commentCount":0,"image":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg","articleSection":["Sin categorizar","Sin categorizar"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/","url":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/","name":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento. - the health","isPartOf":{"@id":"https:\/\/ahelth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#primaryimage"},"image":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg","datePublished":"2022-01-09T21:52:24+00:00","dateModified":"2022-01-11T01:34:19+00:00","author":{"@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"breadcrumb":{"@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#primaryimage","url":"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg","contentUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2022\/01\/breakfast-g05e20e13e_640.jpg","width":640,"height":426,"caption":"Symptoms of excess iodine in the body, causes and treatment"},{"@type":"BreadcrumbList","@id":"https:\/\/ahelth.com\/es\/symptoms-of-excess-iodine-in-the-body-causes-and-treatment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ahelth.com\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00edntomas del exceso de yodo en el organismo, sus causas y tratamiento."}]},{"@type":"WebSite","@id":"https:\/\/ahelth.com\/es\/#website","url":"https:\/\/ahelth.com\/es\/","name":"the health","description":"Articles on health","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahelth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","url":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","contentUrl":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","caption":"admin"},"sameAs":["http:\/\/ahelth.com"],"url":"https:\/\/ahelth.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/posts\/13599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/comments?post=13599"}],"version-history":[{"count":0,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/posts\/13599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/media\/12630"}],"wp:attachment":[{"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/media?parent=13599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/categories?post=13599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahelth.com\/es\/wp-json\/wp\/v2\/tags?post=13599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}