{"id":10270,"date":"2021-12-27T21:42:55","date_gmt":"2021-12-27T21:42:55","guid":{"rendered":"http:\/\/ahelth.com\/%d9%85%d8%b1%d8%b6-%d8%ad%d8%a8-%d8%a7%d9%84%d8%b4%d8%a8%d8%a7%d8%a8-%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b7%d8%a8%d9%8a%d8%a9-%d9%84%d9%83%d9%84-%d9%8a%d9%88%d9%85\/"},"modified":"2021-12-28T19:39:47","modified_gmt":"2021-12-28T19:39:47","slug":"akne-krankheit-medizinische-informationen-fur-jeden-tag","status":"publish","type":"post","link":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/","title":{"rendered":"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\">Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni<\/span><\/span><\/span><\/span><\/p>\n<div>\n<p><em><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;acne<\/span><\/span><\/span><\/span><\/strong><\/em><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> \u00e8 una condizione della pelle che si verifica quando i follicoli piliferi si intasano di oli e cellule morte della pelle. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Causa spesso punti bianchi, punti neri o brufoli e di solito si verifica su viso, fronte, petto, parte superiore della schiena e spalle. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;acne \u00e8 pi\u00f9 comune negli adolescenti, sebbene colpisca persone di tutte le et\u00e0.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-1\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">sintomi dell&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I segni e i sintomi di questa malattia variano a seconda della gravit\u00e0 della sua condizione:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Whiteheads (pori ostruiti).<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Punti neri (pori ostruiti aperti).<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Piccole protuberanze rosse dolorose.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Blister con pus sui bordi.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Grandi protuberanze dure e dolorose sotto la superficie della pelle.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Protuberanze dolorose sotto la superficie della pelle piena di pus (ferite cistiche).<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2 id=\"section-2\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Hai bisogno di vedere un medico<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dovresti consultare il tuo medico di famiglia.Se gli autotrattamenti non aiutano a chiarire la tua acne, lui o lei pu\u00f2 prescrivere farmaci forti. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Se la tua acne persiste o \u00e8 grave, potresti voler vedere un dermatologo per il trattamento.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">In molte donne, l&#8217;acne pu\u00f2 persistere per decenni, con gravi riacutizzazioni nella settimana prima delle mestruazioni, e questo tipo di acne tende a scomparire senza trattamento nelle donne che usano il controllo delle nascite. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;insorgenza improvvisa di acne grave negli anziani pu\u00f2 indicare una condizione medica di base che richiede cure mediche.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La FDA avverte che alcuni prodotti per l&#8217;acne, detergenti e altri prodotti per la pelle possono causare reazioni pericolose. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Queste reazioni sono molto rare, quindi non confonderle con il rossore, l&#8217;irritazione o il prurito che si verificano nel sito di qualsiasi farmaco o applicazione del prodotto.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Consultare un medico di emergenza se si nota uno dei seguenti problemi dopo l&#8217;uso di prodotti per la pelle:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">fatica.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">difficolt\u00e0 respiratorie.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gonfiore degli occhi, del viso, delle labbra o della lingua.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">senso di oppressione alla gola;<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2 id=\"section-3\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cause dell&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ci sono quattro fattori principali che causano l&#8217;acne, che sono i seguenti:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Aumentare la produzione di petrolio.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I follicoli piliferi si intasano di oli e cellule morte della pelle.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">batteri.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Attivit\u00e0 eccessiva di un tipo di ormone (androgeni).<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;acne di solito compare sul viso, sulla fronte, sul petto, sulla parte superiore della schiena e sulle spalle perch\u00e9 queste aree della pelle contengono la maggior parte delle ghiandole sebacee. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I follicoli piliferi sono collegati alle ghiandole sebacee.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La parete follicolare pu\u00f2 gonfiarsi e creare una testa bianca, oppure il gonfiore pu\u00f2 aprirsi sulla superficie e scurirsi, causando un punto nero. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I punti neri possono sembrare sporco bloccato nei pori, ma la verit\u00e0 \u00e8 che i pori sono ostruiti da batteri e oli che diventano marroni se esposti all&#8217;aria.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I brufoli appaiono come macchie rosse con un punto bianco nel mezzo quando i follicoli piliferi chiusi si infiammano o si infettano con batteri. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Il blocco e l&#8217;infiammazione che si verificano in profondit\u00e0 nei follicoli piliferi provocano la comparsa di protuberanze cistiche sotto la superficie della pelle. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Altri pori della pelle, che sono aperture nelle ghiandole sudoripare, di solito non sono associati all&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-4\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Fattori che peggiorano l&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I fattori che possono scatenare o esacerbare l&#8217;acne includono:<\/span><\/span><\/span><\/span><\/p>\n<h4><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">ormone<\/span><\/span><\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gli androgeni sono ormoni che aumentano durante la pubert\u00e0 nei ragazzi e nelle ragazze, causando l&#8217;ingrossamento delle ghiandole sebacee e la produzione di pi\u00f9 grasso. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Anche i cambiamenti ormonali legati alla gravidanza e all&#8217;uso della pillola anticoncezionale possono influenzare la produzione di grasso. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Piccole quantit\u00e0 di androgeni circolano nel sangue delle donne e possono peggiorare l&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<h4><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">qualche medicina<\/span><\/span><\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Esempi sono i medicinali contenenti corticosteroidi, testosterone o litio.<\/span><\/span><\/span><\/span><\/p>\n<h4><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">dieta<\/span><\/span><\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Gli studi dimostrano che alcuni fattori nutrizionali possono peggiorare l&#8217;acne, tra cui latte scremato e cibi ricchi di carboidrati come pane, torte e patatine. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Il cioccolato \u00e8 stato a lungo sospettato di peggiorare l&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Un piccolo studio su 14 uomini con acne ha mostrato che mangiare cioccolato era associato a un peggioramento dei sintomi. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Sono ancora necessari ulteriori studi per scoprire perch\u00e9 questo accade e se le persone con acne traggono beneficio dal seguire determinate restrizioni dietetiche.<\/span><\/span><\/span><\/span><\/p>\n<h4><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">confermare che<\/span><\/span><\/span><\/span><\/h4>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Lo stress pu\u00f2 peggiorare l&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-5\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">miti dell&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I seguenti fattori hanno scarso effetto sull&#8217;acne:<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-5-1\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">cibo grasso<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Mangiare cibi grassi ha poco o nessun effetto sull&#8217;acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Anche se lavorare in un&#8217;area grassa come una padella da cucina pu\u00f2 causare questo, gli oli possono attaccarsi alla pelle e ostruire i follicoli piliferi, causando ulteriore irritazione della pelle o acne.<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-5-2\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Pulizia<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;acne non \u00e8 causata dalla pelle sporca. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">In effetti, strofinare la pelle troppo energicamente o strofinare con saponi aggressivi o prodotti chimici pu\u00f2 irritare la pelle e peggiorare l&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-5-3\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Foto<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I cosmetici non aggravano necessariamente l&#8217;acne, soprattutto se usi cosmetici senza olio che non ostruiscono i pori e rimuovono regolarmente il trucco. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">E i cosmetici non grassi non influiscono sull&#8217;efficacia dei farmaci per l&#8217;acne.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-6\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">fattori di rischio dell&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I fattori di rischio per questa malattia sono:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Et\u00e0 Persone di qualsiasi et\u00e0 possono sviluppare la malattia, ma \u00e8 pi\u00f9 comune negli adolescenti.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cambiamenti ormonali: questi cambiamenti sono comuni negli adolescenti, nelle donne, nelle ragazze e nelle persone che assumono determinati farmaci, compresi quelli contenenti corticosteroidi, androgeni o litio.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Una storia familiare di fattori genetici nell&#8217;acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Se entrambi i genitori hanno questa condizione, probabilmente lo farai.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Sostanze oleose o grasse Questa condizione pu\u00f2 verificarsi quando la pelle viene a contatto con lozioni, creme o oli grassi sul posto di lavoro, ad esempio in cucina.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Attrito o pressione sulla pelle che possono essere causati da cose come telefoni cellulari, caschi, colletti stretti e zaini.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Lo stress non causa l&#8217;acne, ma se lo hai gi\u00e0, pu\u00f2 peggiorarlo.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2 id=\"section-7\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Trattamento per l&#8217;acne<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Se hai provato prodotti per l&#8217;acne da banco per diverse settimane e non hanno funzionato, il medico potrebbe prescriverti farmaci pi\u00f9 potenti. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Un dermatologo pu\u00f2 aiutarti con:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Combatti l&#8217;acne.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Evita cicatrici o altri danni alla pelle.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ridurre l&#8217;aspetto delle cicatrici.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I farmaci per l&#8217;acne agiscono riducendo i prodotti oleosi, accelerando la trasformazione delle cellule della pelle, combattendo le infezioni batteriche o riducendo l&#8217;infiammazione, prevenendo cos\u00ec le cicatrici. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La maggior parte dei farmaci per l&#8217;acne pu\u00f2 richiedere da quattro a otto settimane per vedere i risultati e la pelle potrebbe deteriorarsi prima che migliori. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Potrebbero essere necessari diversi mesi o anni prima che l&#8217;acne si risolva completamente.<\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Il regime di trattamento consigliato dal medico dipende dalla tua et\u00e0, dal tipo e dalla gravit\u00e0 dell&#8217;acne e dalle cose a cui vuoi attenerti. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Potrebbe essere necessario lavare la pelle interessata e applicarvi dei farmaci due volte al giorno per diverse settimane. <\/span><span style=\"vertical-align: inherit;\">I farmaci topici e quelli assunti per via orale sono spesso usati insieme. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Le donne in gravidanza non possono assumere farmaci per via orale prescritti per l&#8217;acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Parla con il tuo medico dei rischi e dei benefici dei farmaci e degli altri trattamenti che stai prendendo in considerazione.<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-7-1\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">farmaci topici<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">I farmaci topici pi\u00f9 comuni per l&#8217;acne includono:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Retinoidi e farmaci simili ai retinoidi.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Antibiotici.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Acido salicilico e acido azelaico.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dobson.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h3 id=\"section-7-2\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Orale<\/span><\/span><\/span><\/span><\/h3>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Antibiotici.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Contraccettivi orali combinati.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Antiandrogeni.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Isotretinoina.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h3 id=\"section-7-3\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Trattamenti<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">In alcuni casi selezionati, i seguenti trattamenti possono essere raccomandati da soli o in combinazione con farmaci:<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-7-4\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">trattamento dei bambini<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La maggior parte degli studi sui farmaci per l&#8217;acne sono stati utilizzati in persone di et\u00e0 pari o superiore a 12 anni. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Anche i bambini pi\u00f9 piccoli hanno sempre pi\u00f9 acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">In uno studio su 365 ragazze di et\u00e0 compresa tra 9 e 10 anni, \u00e8 stato riscontrato che il 78% di loro ha avuto sfoghi di acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Se tuo figlio ha l&#8217;acne, consulta un dermatologo pediatrico. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Chiedi informazioni sui farmaci che i bambini dovrebbero evitare, sulle dosi appropriate, sulle interazioni farmacologiche, sugli effetti collaterali e su come il trattamento influenzer\u00e0 la crescita e lo sviluppo di tuo figlio.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-8\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Stile di vita e alcuni rimedi casalinghi<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Puoi provare a prevenire o controllare l&#8217;acne lieve con prodotti da banco, una buona cura della pelle e altre tecniche di cura di s\u00e9, come segue:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span class=\"\" style=\"vertical-align: inherit;\">Lavare le aree interessate con una lozione delicata e alcuni prodotti come scrub per il viso, tappi per vasi sanguigni e maschere per il viso dovrebbero essere evitati. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Anche l&#8217;eccessiva esfoliazione e lo sfregamento possono irritare la pelle.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Prova i prodotti da banco per l&#8217;acne che contengono perossido di benzoile come ingrediente efficace per asciugare l&#8217;olio in eccesso e favorire l&#8217;esfoliazione. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Si possono provare anche prodotti contenenti acido salicilico o alfa idrossiacidi.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Evita sostanze irritanti come prodotti di bellezza grassi o grassi, creme solari, prodotti per lo styling dei capelli o prodotti usati per mascherare l&#8217;acne.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Proteggi la tua pelle dal sole Il sole peggiora l&#8217;acne per alcune persone.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Evita di strofinare o esercitare pressione sulla pelle e proteggi la tua pelle a tendenza acneica dal contatto con oggetti come telefoni, caschi, colletti o cinture strette e zaini.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Evita di toccare o strappare le aree interessate poich\u00e9 ci\u00f2 pu\u00f2 portare a pi\u00f9 acne, infezioni o cicatrici.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dopo attivit\u00e0 faticose, la doccia con olio e sudore sulla pelle pu\u00f2 portare a sfoghi di acne.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h2 id=\"section-9\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">trattamento alternativo<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Trattamenti complementari e alternativi per l&#8217;acne vulgaris includono olio di pesce, lievito di birra, probiotici, zinco orale e olio topico dell&#8217;albero del t\u00e8. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Sono necessarie ulteriori ricerche per determinare la potenziale efficacia e sicurezza a lungo termine di questi altri approcci integrativi come il biofeedback e la medicina tradizionale cinese. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Parla con il tuo medico dei pro e dei contro di alcuni trattamenti prima di provarli.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-10\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Affrontare la malattia e il supporto<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">L&#8217;acne e le cicatrici da acne possono causare ansia e influenzare le relazioni sociali e l&#8217;immagine di s\u00e9. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">A volte pu\u00f2 essere utile parlare con la tua famiglia, un gruppo di supporto o un consulente. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">E lo stress pu\u00f2 aggravare l&#8217;acne. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cerca di controllare lo stress dormendo a sufficienza e usando tecniche di rilassamento.<\/span><\/span><\/span><\/span><\/p>\n<h2 id=\"section-11\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Preparazione per un appuntamento dal medico<\/span><\/span><\/span><\/span><\/h2>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Prendi un appuntamento con il tuo medico se hai l&#8217;acne che non risponde ai trattamenti di autocura e da banco. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Un trattamento efficace dell&#8217;acne precoce ridurr\u00e0 il rischio di cicatrici e danni permanenti alla propria autostima. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dopo l&#8217;esame iniziale, il medico pu\u00f2 indirizzarti a uno specialista nella diagnosi e nel trattamento delle condizioni della pelle. <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Le seguenti informazioni ti aiuteranno a prepararti per il tuo appuntamento.<\/span><\/span><\/span><\/span><\/p>\n<h3 id=\"section-11-1\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cosa dovrei fare?<\/span><\/span><\/span><\/span><\/h3>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Fai un elenco di importanti informazioni mediche come altre condizioni mediche con cui potresti avere a che fare e qualsiasi prodotto da prescrizione o da banco che usi, comprese vitamine e integratori.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Fai un elenco di informazioni personali, inclusi eventuali stress importanti o cambiamenti di vita recenti.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Scrivi una domanda da porre al tuo medico.<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Alcune domande da porre al medico sono:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Che trattamenti mi consigliate?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Se il primo trattamento non funziona, cosa consigli dopo?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quali sono i possibili effetti collaterali dei farmaci che stai prescrivendo?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Per quanto tempo posso usare in sicurezza i farmaci che mi prescrive?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quando i sintomi iniziano a migliorare dopo l&#8217;inizio del trattamento?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quando mi rivedrai per vedere se il mio trattamento ha funzionato?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00c8 sicuro interrompere l&#8217;assunzione di un farmaco se non sembra funzionare?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quali misure di auto-cura posso intraprendere per migliorare i sintomi?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Mi consigliate di cambiare la mia dieta?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Consiglieresti di apportare modifiche ai prodotti da banco che uso sulla mia pelle, inclusi saponi, lozioni, creme solari e cosmetici?<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<h3 id=\"section-11-2\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Cosa ti aspetti dal tuo medico?<\/span><\/span><\/span><\/span><\/h3>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00c8 probabile che il medico ti faccia una serie delle seguenti domande:<\/span><\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quando hai riscontrato per la prima volta questo problema?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">C&#8217;\u00e8 qualcosa che sembra causare l&#8217;acne, come lo stress o la sindrome premestruale nelle donne e nelle ragazze?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quali farmaci prendi, inclusi farmaci da prescrizione e da banco, vitamine e integratori alimentari?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Usi contraccettivi orali per ragazze e donne?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Per le ragazze e le donne, hai periodi mestruali regolari?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Per ragazze e donne Sei incinta o stai pianificando di rimanere incinta presto?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Che tipo di saponi, lozioni, creme solari, prodotti per capelli o cosmetici usi?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">In che modo l&#8217;acne influisce sulla tua autostima e fiducia nelle situazioni sociali?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Hai una storia familiare di acne?<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Quali trattamenti e passaggi di cura di s\u00e9 hai provato finora? <\/span><\/span><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Alcuni di loro erano efficaci?<\/span><\/span><\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni L&#8217;acne \u00e8 una condizione della pelle che si verifica quando i follicoli piliferi si intasano di oli e cellule morte della pelle. Causa spesso punti bianchi, punti neri o brufoli e di solito si verifica su viso, fronte, petto, parte superiore della schiena e spalle. L&#8217;acne &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-10270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malattia dell&#039;acne - informazioni mediche per tutti i giorni - the health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malattia dell&#039;acne - informazioni mediche per tutti i giorni - the health\" \/>\n<meta property=\"og:description\" content=\"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni L&#8217;acne \u00e8 una condizione della pelle che si verifica quando i follicoli piliferi si intasano di oli e cellule morte della pelle. Causa spesso punti bianchi, punti neri o brufoli e di solito si verifica su viso, fronte, petto, parte superiore della schiena e spalle. L&#8217;acne &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/\" \/>\n<meta property=\"og:site_name\" content=\"the health\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-27T21:42:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-28T19:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"headline\":\"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni\",\"datePublished\":\"2021-12-27T21:42:55+00:00\",\"dateModified\":\"2021-12-28T19:39:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/\"},\"wordCount\":2032,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/struggle-gdeafa16e6_640.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/\",\"url\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/\",\"name\":\"Malattia dell'acne - informazioni mediche per tutti i giorni - the health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/struggle-gdeafa16e6_640.jpg\",\"datePublished\":\"2021-12-27T21:42:55+00:00\",\"dateModified\":\"2021-12-28T19:39:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/struggle-gdeafa16e6_640.jpg\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/struggle-gdeafa16e6_640.jpg\",\"width\":640,\"height\":426,\"caption\":\"Akne-Krankheit - medizinische Informationen f\u00fcr jeden Tag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/akne-krankheit-medizinische-informationen-fur-jeden-tag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ahelth.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ahelth.com\\\/es\\\/\",\"name\":\"the health\",\"description\":\"Articles on health\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ahelth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/ahelth.com\"],\"url\":\"https:\\\/\\\/ahelth.com\\\/it\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malattia dell'acne - informazioni mediche per tutti i giorni - the health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/","og_locale":"it_IT","og_type":"article","og_title":"Malattia dell'acne - informazioni mediche per tutti i giorni - the health","og_description":"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni L&#8217;acne \u00e8 una condizione della pelle che si verifica quando i follicoli piliferi si intasano di oli e cellule morte della pelle. Causa spesso punti bianchi, punti neri o brufoli e di solito si verifica su viso, fronte, petto, parte superiore della schiena e spalle. L&#8217;acne &hellip;","og_url":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/","og_site_name":"the health","article_published_time":"2021-12-27T21:42:55+00:00","article_modified_time":"2021-12-28T19:39:47+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#article","isPartOf":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/"},"author":{"name":"admin","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"headline":"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni","datePublished":"2021-12-27T21:42:55+00:00","dateModified":"2021-12-28T19:39:47+00:00","mainEntityOfPage":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/"},"wordCount":2032,"commentCount":0,"image":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/","url":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/","name":"Malattia dell'acne - informazioni mediche per tutti i giorni - the health","isPartOf":{"@id":"https:\/\/ahelth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#primaryimage"},"image":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg","datePublished":"2021-12-27T21:42:55+00:00","dateModified":"2021-12-28T19:39:47+00:00","author":{"@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"breadcrumb":{"@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#primaryimage","url":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg","contentUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/12\/struggle-gdeafa16e6_640.jpg","width":640,"height":426,"caption":"Akne-Krankheit - medizinische Informationen f\u00fcr jeden Tag"},{"@type":"BreadcrumbList","@id":"https:\/\/ahelth.com\/it\/akne-krankheit-medizinische-informationen-fur-jeden-tag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ahelth.com\/it\/"},{"@type":"ListItem","position":2,"name":"Malattia dell&#8217;acne &#8211; informazioni mediche per tutti i giorni"}]},{"@type":"WebSite","@id":"https:\/\/ahelth.com\/es\/#website","url":"https:\/\/ahelth.com\/es\/","name":"the health","description":"Articles on health","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahelth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","url":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","contentUrl":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","caption":"admin"},"sameAs":["http:\/\/ahelth.com"],"url":"https:\/\/ahelth.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts\/10270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/comments?post=10270"}],"version-history":[{"count":0,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts\/10270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/media\/10254"}],"wp:attachment":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/media?parent=10270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/categories?post=10270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/tags?post=10270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}