{"id":3759,"date":"2021-11-19T22:40:50","date_gmt":"2021-11-19T22:40:50","guid":{"rendered":"http:\/\/ahelth.com\/?p=3759"},"modified":"2021-11-19T22:40:50","modified_gmt":"2021-11-19T22:40:50","slug":"vitamin-d-supplement-risks","status":"publish","type":"post","link":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/","title":{"rendered":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D"},"content":{"rendered":"<div id=\"block-5f84d6f7a4909814a9cae7ec\" class=\"sqs-block html-block sqs-block-html\" data-block-type=\"2\">\n<div class=\"sqs-block-content\">\n<h1><strong><span><span class=\"\">Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D<\/span><\/span><\/strong><\/h1>\n<\/div>\n<\/div>\n<div id=\"block-yui_3_17_2_1_1608771436017_8255\" class=\"sqs-block gallery-block sqs-block-gallery\" data-block-json=\"{&quot;hSize&quot;:null,&quot;floatDir&quot;:null,&quot;methodOption&quot;:&quot;transient&quot;,&quot;existingGallery&quot;:null,&quot;newWindow&quot;:false,&quot;aspect-ratio&quot;:&quot;square&quot;,&quot;aspectRatio&quot;:null,&quot;auto-crop&quot;:true,&quot;blockAnimation&quot;:&quot;none&quot;,&quot;collectionId&quot;:&quot;5fe3e786f9071f76001c13da&quot;,&quot;design&quot;:&quot;grid&quot;,&quot;lightbox&quot;:false,&quot;padding&quot;:20,&quot;show-meta&quot;:true,&quot;show-meta-basic&quot;:true,&quot;show-meta-only-title&quot;:false,&quot;show-meta-only-description&quot;:false,&quot;square-thumbs&quot;:true,&quot;thumbnails-per-row&quot;:3,&quot;vSize&quot;:null,&quot;transientGalleryId&quot;:&quot;5fe3e786f9071f76001c13da&quot;}\" data-block-type=\"8\">\n<div class=\"sqs-block-content\">\n<div id=\"yui_3_17_2_1_1635947906345_161\" class=\"\n  sqs-gallery-container\n  sqs-gallery-block-grid\n  sqs-gallery-aspect-ratio-square\n  sqs-gallery-thumbnails-per-row-3\n\n  sqs-gallery-block-show-meta\n\n  block-animation-none\n  clear\"><\/p>\n<p>&nbsp;<\/p>\n<div id=\"yui_3_17_2_1_1635947906345_178\" class=\"sqs-gallery sqs-gallery-design-grid\">\n<div id=\"yui_3_17_2_1_1635947906345_212\" class=\"slide sqs-gallery-design-grid-slide\" data-type=\"image\" data-animation-role=\"image\">\n<div class=\"margin-wrapper\"><\/div>\n<\/div>\n<div id=\"yui_3_17_2_1_1635947906345_214\" class=\"slide sqs-gallery-design-grid-slide\" data-type=\"image\" data-animation-role=\"image\">\n<div class=\"margin-wrapper\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"block-yui_3_17_2_1_1608771436017_8382\" class=\"sqs-block html-block sqs-block-html\" data-block-type=\"2\">\n<div class=\"sqs-block-content\">\n<h2><span>La luce del sole \u00e8 necessaria\u00a0<\/span><\/h2>\n<p class=\"\"><span>Come la maggior parte della vita sulla Terra, gli esseri umani hanno bisogno di aria pulita, acqua, cibo e luce solare per sopravvivere. Tutta la vita si evolve per sfruttare i nutrienti disponibili nell&#8217;ambiente e, istintivamente, la maggior parte di noi sa che questo include il potere del sole. C&#8217;\u00e8 un&#8217;abbondanza di avvincenti ricerche scientifiche che confermano il nostro desiderio innato di uscire in una giornata di sole per assorbire quei raggi. <span class=\"\">Questa ricerca dimostra che la vitamina D che il nostro corpo produce utilizzando la luce solare \u00e8 essenziale per il nostro benessere e la nostra sopravvivenza.\u00a0<\/span><\/span><\/p>\n<p class=\"\"><span>La recente ricerca medica si \u00e8 concentrata sulla vitamina D e sul suo ruolo non solo nella salute delle ossa, ma anche nella prevenzione della depressione, del cancro e di altre malattie. Questi studi mostrano costantemente che una maggiore quantit\u00e0 di vitamina D dalla luce solare \u00e8 associata a una migliore funzione fisica, mentale e immunitaria. Tuttavia, gli studi sull&#8217;integrazione di vitamina D non mostrano gli stessi effetti sulla salute. Perch\u00e9 gli integratori di vitamina D per via orale non sono sufficienti? Perch\u00e9, infatti, l&#8217;integrazione a volte aggrava il problema o, come mostrano ricerche recenti, causa nuovi problemi?\u00a0<\/span><\/p>\n<p class=\"\"><span>La risposta sta nella comprensione del complesso sistema che i nostri corpi usano naturalmente per fornirci vitamina D in modo efficiente e sicuro. I nostri corpi si sono evoluti per produrre molti ormoni benefici, inclusa la vitamina D, quando la nostra pelle \u00e8 esposta alla luce solare. Quando trascorriamo una giornata al sole, possiamo preoccuparci delle scottature, ma non ci preoccupiamo mai di un&#8217;overdose di vitamina D.\u00a0<\/span><\/p>\n<p class=\"\"><span>Sorprendentemente, il corpo ha sviluppato un sistema infallibile per impedirci di assumere troppa vitamina D quando \u00e8 prodotta dalla luce solare e prodotta nella nostra pelle. Infatti, la vitamina D \u00e8 regolata nel corpo umano solo quando la vitamina D si forma nella pelle, mentre la vitamina D assorbita attraverso lo stomaco aggira questa protezione di base.\u00a0<\/span><\/p>\n<h2><span>Proteina legante la vitamina D (DBP)\u00a0<\/span><\/h2>\n<p class=\"\"><span>Al centro di questo sistema si trova la proteina vitamina D (DBP). Questa proteina \u00e8 la forza per assicurarci di ottenere sempre esattamente la quantit\u00e0 di vitamina D di cui abbiamo bisogno. Il DBP controlla l&#8217;apporto di vitamina D e la biodisponibilit\u00e0 di vitamina D e calcitriolo, un ormone pro-steroideo che \u00e8 la forma attiva della vitamina D. Il DBP \u00e8 una proteina multifunzionale che si trova in azione ovunque nel corpo: nel sangue, nel liquido ascitico, e liquido cerebrospinale, nonch\u00e9 sulla superficie di molti tipi di cellule. [1] Il ruolo principale della DBP \u00e8 di mantenere depositi stabili di metaboliti della vitamina D nel siero e di modulare la biodisponibilit\u00e0, l&#8217;attivazione e le velocit\u00e0 di rilascio a livello cellulare. Il fegato produce 25-idrossivitamina D e calitriolo prodotti nei reni) e li trasporta ai tessuti bersaglio.\u00a0<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"row sqs-row\">\n<div class=\"col sqs-col-2 span-2\">\n<div id=\"block-yui_3_17_2_1_1631310293802_16466\" class=\"sqs-block spacer-block sqs-block-spacer sized vsize-1\" data-block-type=\"21\">\n<div class=\"sqs-block-content\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"block-yui_3_17_2_1_1631310293802_8899\" class=\"sqs-block html-block sqs-block-html\" data-block-type=\"2\">\n<div class=\"sqs-block-content\">\n<h2><span>\u00a0Integrazione di vitamina D contro la luce solare<\/span><\/h2>\n<p class=\"\"><span>Quando la pelle \u00e8 esposta alla luce solare, in particolare alla luce nello spettro ultravioletto B (UVB), innesca un rilascio lento e prolungato di vitamina D con conseguente concentrazione elevata e costante di vitamina D per diversi giorni. Quando la luce colpisce il corpo, converte il colesterolo negli strati superiori della pelle in pre-vitamina D3. Tuttavia, il DBP non si legher\u00e0 a questa forma di vitamina D per il trasporto. In primo luogo, la pelle deve convertire la vitamina D3 in vitamina D3. Solo allora DBP la raccoglier\u00e0 per la consegna accuratamente misurata dalla pelle nel flusso sanguigno nel corso di diversi giorni. Questi controlli interni determinano un flusso lento e costante di vitamina D3 nel fegato che persiste per pi\u00f9 di due settimane. Il corpo si \u00e8 evoluto per garantire che la vitamina D3 non raggiunga il fegato troppo rapidamente. Dopo aver raggiunto il fegato,\u00a0<\/span><\/p>\n<p class=\"\"><span>D&#8217;altra parte, l&#8217;assunzione di vitamina D aggira tutti i processi regolatori nel corpo e consente alla vitamina D di essere trasportata e assorbita dal fegato entro poche ore. Colesterolo cattivo (colesterolo cattivo). La vitamina D3 viene consegnata al fegato tramite DBP lentamente e costantemente come parte di una molecola idrosolubile, mentre la vitamina D3 proveniente dallo stomaco raggiunge la parte posteriore del colesterolo e dei grassi in un enorme deposito che richiede un&#8217;elaborazione immediata. In questo modo, l&#8217;integrazione di vitamina D aggira i regolatori naturali della produzione e della distribuzione nell&#8217;organismo. Senza DBP per monitorare la consegna o l&#8217;assorbimento, l&#8217;integrazione orale di vitamina D offre un&#8217;esperienza simile a montagne russe, festa o fame nella disponibilit\u00e0 di vitamina D. [9] In casi estremi, forti aumenti improvvisi di vitamina D dovuti all&#8217;assunzione di integratori alimentari possono aumentare l&#8217;assorbimento del calcio nel sangue (ipercalcemia) e sovraccaricare il fegato e i reni, che non sono progettati per ricevere tali dosi concentrate.Sebbene la tossicit\u00e0 della vitamina D sia rara, \u00e8 stata osservata come risultato dell&#8217;assunzione di grandi dosi di vitamina D supplementare per lunghi periodi di tempo. Gli integratori forniscono un apporto intermittente, inaffidabile e di breve durata di vitamina D.\u00a0<\/span><\/p>\n<h2><span>Gli integratori di vitamina D funzionano?<\/span><\/h2>\n<p class=\"\"><span>Gli integratori orali di vitamina D non sono efficaci per un numero sorprendentemente elevato di persone. Il corpo umano \u00e8 progettato per produrre vitamina D attraverso la pelle quando esposto alla luce solare, piuttosto che assorbire questo importante ormone attraverso il sistema digestivo. \u00c8 stato dimostrato che l&#8217;assunzione supplementare di vitamina D non \u00e8 correlata correttamente, con non pi\u00f9 del 60% associato con DBP negli esseri umani.\u00a0<\/span><\/p>\n<p class=\"\"><span>Inoltre, circa 32 milioni di americani hanno un malassorbimento dei grassi (fibrosi cistica, morbo di Crohn, celiachia, malattie del fegato, ecc.) che impedisce loro di assorbire integratori di vitamina D liposolubili, eppure i loro corpi possono produrre grandi quantit\u00e0 di vitamina D dai raggi UV . una luce. Poich\u00e9 gli integratori eludono il processo naturale del corpo di regolare la vitamina D e non si legano correttamente al DBP, non sono efficaci per sostenere la salute sistemica allo stesso modo della vitamina D derivata dalla luce solare.\u00a0<\/span><\/p>\n<h2><span>Raggiungere il giusto equilibrio\u00a0<\/span><\/h2>\n<p class=\"\"><span>I nostri corpi sono programmati per determinare i livelli ottimali di vitamina D e lavorano con la luce solare per mantenerci in perfetto equilibrio. \u00c8 noto che una maggiore concentrazione di vitamina D in circolo \u00e8 associata a un minor rischio di molte malattie croniche, inclusi i tumori comuni, le malattie autoimmuni, le malattie infettive e le malattie cardiovascolari. Tuttavia, ci sono diversi studi che hanno mostrato un&#8217;associazione a forma di U sconcertante, in cui livelli bassi e alti di vitamina D portano ad un aumento del rischio di alcuni tumori, esiti cardiovascolari negativi e mortalit\u00e0. Ha anche dimostrato che mentre alti livelli di vitamina D dal sole sono utili nella prevenzione del cancro al seno e della depressione, l&#8217;integrazione di vitamina D non fornisce tale beneficio. Ci\u00f2 indica che sebbene la carenza di vitamina D sia un problema, assumere troppa vitamina D attraverso gli integratori non \u00e8 vantaggioso e pu\u00f2 anche causare problemi.Questa ricerca mostra che dobbiamo stare attenti a non aumentare troppo i nostri livelli di vitamina D con gli integratori, perch\u00e9 andiamo oltre la zona mediana ottimale e finiamo per causare nuovi problemi inaspettati a livello cellulare o, in casi estremi, tossicit\u00e0. Come con qualsiasi ormone, i livelli di vitamina D devono essere regolati con precisione per aiutare il corpo a funzionare correttamente e questo deriva solo dall&#8217;esposizione al corretto spettro della luce solare.\u00a0<\/span><\/p>\n<p class=\"\"><span>Per rendere le cose pi\u00f9 complicate, quell&#8217;ambito posto nel mezzo che aiuta a combattere le malattie e a prevenire le malattie varia da persona a persona. I nostri corpi si sono evoluti per regolare, produrre e distribuire la quantit\u00e0 unica di vitamina D di cui un individuo ha bisogno. Ci\u00f2 rende quasi impossibile determinare e mantenere un livello ottimale per un individuo attraverso l&#8217;integrazione orale. L&#8217;unico modo per ottimizzare veramente la vitamina D per una salute sistemica ottimale \u00e8 consentire al corpo di fare ci\u00f2 che sa fare meglio: l&#8217;autoregolazione della produzione e del rilascio attraverso l&#8217;esposizione alla pelle.\u00a0<\/span><\/p>\n<h2><span>Benefici della luce solare\u00a0<\/span><\/h2>\n<p class=\"\"><span>Quando la pelle umana \u00e8 esposta alla luce solare, produce molti ormoni e peptidi che contribuiscono alla salute e al benessere generale. Le sostanze ottenute da reazioni chimiche con la luce solare sono chiamate prodotti fotovoltaici. Sebbene la vitamina D sia il beneficio per la salute pi\u00f9 universalmente riconosciuto che gli esseri umani ricevono dall&#8217;esposizione alla luce solare, \u00e8 solo uno dei tanti importanti prodotti della fotosintesi.\u00a0<\/span><\/p>\n<p class=\"\"><span>Oltre alla vitamina D3, altri prodotti fotovoltaici sani realizzati nella stessa gamma di lunghezze d&#8217;onda UV includono: calcitonina del gene che lega i peptidi, sostanza neuropeptidica P, ormone adrenocorticotropo, ormone stimolante i melanociti, calcitriolo e beta-endorfine.<\/span><\/p>\n<p class=\"\"><span>Questi prodotti fotodinamici hanno un effetto ad ampio spettro sul corpo e sono coinvolti nella regolazione del sistema immunitario, promuovendo un flusso sanguigno sano, riducendo l&#8217;infiammazione, agendo come antidolorifici naturali e altro ancora. Tutte queste sostanze contribuiscono alla sensazione di relax e felicit\u00e0 che proviamo quando siamo regolarmente esposti al sole.\u00a0<\/span><\/p>\n<h2><span>Dovrei prendere pillole di vitamina D?<\/span><\/h2>\n<p class=\"\"><span>Prima di ricorrere alla supplementazione di vitamina D per sostenere la salute, considera le differenze tra le pillole di vitamina D e la luce solare. L&#8217;associazione tra elevati livelli ematici di vitamina D e prevenzione delle malattie nella ricerca epidemiologica misura effettivamente l&#8217;esposizione alla luce solare piuttosto che la vitamina D supplementare, e studi sulla popolazione hanno ripetutamente dimostrato che l&#8217;esposizione alla luce solare contribuisce alla concentrazione di vitamina D pi\u00f9 del consumo orale. ] Pertanto, a livello di popolazione, la vitamina D \u00e8 in realt\u00e0 una misura dell&#8217;esposizione alla luce solare e concentrazioni sieriche pi\u00f9 elevate sono un indicatore di un maggiore contatto della pelle con la luce solare.\u00a0<\/span><\/p>\n<p class=\"\"><span>Supponendo che il livello di vitamina D nel corpo da un integratore alimentare orale rappresenti gli stessi benefici per la salute della vitamina D derivata dalla luce, non tiene conto dell&#8217;effetto della luce solare sulla salute umana al di fuori della produzione di vitamina D. \u00c8 importante tenere presente che ci sono altri prodotti biofotonici che contribuiscono alla salute del nostro sistema oltre alla vitamina D.\u00a0<\/span><\/p>\n<h2><span>Puoi assumere troppa vitamina D?<\/span><\/h2>\n<p class=\"\"><span>Se riesci ad assumere molta vitamina D, tutto dipende dalla fonte della tua vitamina D: luce solare contro integratori. Non puoi overdose di vitamina D3 che \u00e8 stimolata dalla luce e prodotta nella tua pelle. Se hai abbastanza vitamina D, il tuo corpo ne produrr\u00e0 di meno. L&#8217;uso della luce per produrre vitamina D consente al tuo corpo di autoregolare la produzione e produrre ci\u00f2 di cui ha bisogno per rimanere in salute, senza il rischio di sovradosaggio o tossicit\u00e0. Gli integratori orali, siano essi compresse, liquidi o spray di vitamina D, presentano rischi di tossicit\u00e0 da vitamina D e sintomi potenzialmente gravi.\u00a0<\/span><\/p>\n<h2><span>Cosa succede quando si assumono troppi integratori di vitamina D?<\/span><\/h2>\n<p class=\"\"><span>Prima di assumere un integratore di vitamina D deglutibile, \u00e8 importante chiedersi: &#8220;Quanta vitamina D dovrei assumere?&#8221; Le linee guida per il trattamento della carenza di vitamina D variano ampiamente tra le diverse autorit\u00e0 mediche. L&#8217;indennit\u00e0 dietetica raccomandata dall&#8217;Istituto di Medicina (IOM) \u00e8 di 600 unit\u00e0 internazionali (UI) al giorno. <span class=\"\">Molti ricercatori sulla vitamina D non sono d&#8217;accordo con questa raccomandazione e affermano che l&#8217;indennit\u00e0 raccomandata dall&#8217;IOM non \u00e8 sufficiente per prevenire la carenza o sostenere la salute delle ossa. <\/span>In generale, 4.000 UI o meno al giorno sono considerate sicure, purch\u00e9 i valori del sangue siano monitorati.<\/span><\/p>\n<p class=\"\"><span>\u00c8 necessario evitare dosi eccessive di vitamina D per via orale, se l&#8217;assunzione di vitamina D \u00e8 troppo elevata, pu\u00f2 causare tossicit\u00e0 da vitamina D, nota anche come ipervitaminosi D. . La tossicit\u00e0 della vitamina D \u00e8 piuttosto rara, ma \u00e8 stata notata come un effetto collaterale delle pillole di vitamina D ad alte dosi se assunte per lunghi periodi di tempo.\u00a0<\/span><\/p>\n<h2><span>Sintomi di integratori di vitamina D eccessivi<\/span><\/h2>\n<p class=\"\"><span>Quando si assumono integratori di vitamina D per via orale, \u00e8 importante conoscere ed essere in grado di riconoscere i sintomi della tossicit\u00e0 della vitamina D. Quello che succede quando prendi troppa vitamina D pu\u00f2 variare da persona a persona. Gli effetti collaterali dell&#8217;assunzione di troppa vitamina D possono includere diarrea, stitichezza e mal di stomaco. Distress digestivo, sete estrema o minzione frequente possono essere segni di assunzione di troppa vitamina D.<\/span><\/p>\n<p class=\"\"><span>Se si verifica uno di questi effetti collaterali durante l&#8217;assunzione di compresse, compresse, spray o liquidi di vitamina D per via orale, \u00e8 necessario contattare il medico poich\u00e9 potrebbero essere segni di alti livelli di calcio e tossicit\u00e0 della vitamina D.<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D &nbsp; La luce del sole \u00e8 necessaria\u00a0 Come la maggior parte della vita sulla Terra, gli esseri umani hanno bisogno di aria pulita, acqua, cibo e luce solare per sopravvivere. Tutta la vita si evolve per sfruttare i nutrienti disponibili nell&#8217;ambiente e, istintivamente, la &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[863,862,864,865],"class_list":["post-3759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-effetti-collaterali","tag-limitazioni","tag-tossicita-e-rischi-della-supplementazione-di-vitamina-d","tag-vitamin-d-supplement-risks-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health\" \/>\n<meta property=\"og:description\" content=\"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D &nbsp; La luce del sole \u00e8 necessaria\u00a0 Come la maggior parte della vita sulla Terra, gli esseri umani hanno bisogno di aria pulita, acqua, cibo e luce solare per sopravvivere. Tutta la vita si evolve per sfruttare i nutrienti disponibili nell&#8217;ambiente e, istintivamente, la &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/\" \/>\n<meta property=\"og:site_name\" content=\"the health\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-19T22:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"headline\":\"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D\",\"datePublished\":\"2021-11-19T22:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/\"},\"wordCount\":2071,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/vitamin-d-supplement-risks.jpg\",\"keywords\":[\"effetti collaterali\",\"Limitazioni\",\"tossicit\u00e0 e rischi della supplementazione di vitamina D\",\"vitamin-d-supplement-risks\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/\",\"url\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/\",\"name\":\"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/vitamin-d-supplement-risks.jpg\",\"datePublished\":\"2021-11-19T22:40:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/vitamin-d-supplement-risks.jpg\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/vitamin-d-supplement-risks.jpg\",\"width\":1280,\"height\":960,\"caption\":\"vitamin-d-supplement-risks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/it\\\/vitamin-d-supplement-risks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ahelth.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ahelth.com\\\/es\\\/\",\"name\":\"the health\",\"description\":\"Articles on health\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ahelth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/es\\\/#\\\/schema\\\/person\\\/ac5d2a0af0e99e510259404003db4164\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"url\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"contentUrl\":\"https:\\\/\\\/ahelth.com\\\/wp-content\\\/litespeed\\\/avatar\\\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/ahelth.com\"],\"url\":\"https:\\\/\\\/ahelth.com\\\/it\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/","og_locale":"it_IT","og_type":"article","og_title":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health","og_description":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D &nbsp; La luce del sole \u00e8 necessaria\u00a0 Come la maggior parte della vita sulla Terra, gli esseri umani hanno bisogno di aria pulita, acqua, cibo e luce solare per sopravvivere. Tutta la vita si evolve per sfruttare i nutrienti disponibili nell&#8217;ambiente e, istintivamente, la &hellip;","og_url":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/","og_site_name":"the health","article_published_time":"2021-11-19T22:40:50+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#article","isPartOf":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/"},"author":{"name":"admin","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"headline":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D","datePublished":"2021-11-19T22:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/"},"wordCount":2071,"commentCount":0,"image":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg","keywords":["effetti collaterali","Limitazioni","tossicit\u00e0 e rischi della supplementazione di vitamina D","vitamin-d-supplement-risks"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/","url":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/","name":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D - the health","isPartOf":{"@id":"https:\/\/ahelth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#primaryimage"},"image":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#primaryimage"},"thumbnailUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg","datePublished":"2021-11-19T22:40:50+00:00","author":{"@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164"},"breadcrumb":{"@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#primaryimage","url":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg","contentUrl":"https:\/\/ahelth.com\/wp-content\/uploads\/2021\/11\/vitamin-d-supplement-risks.jpg","width":1280,"height":960,"caption":"vitamin-d-supplement-risks"},{"@type":"BreadcrumbList","@id":"https:\/\/ahelth.com\/it\/vitamin-d-supplement-risks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ahelth.com\/it\/"},{"@type":"ListItem","position":2,"name":"Limitazioni, effetti collaterali, tossicit\u00e0 e rischi della supplementazione di vitamina D"}]},{"@type":"WebSite","@id":"https:\/\/ahelth.com\/es\/#website","url":"https:\/\/ahelth.com\/es\/","name":"the health","description":"Articles on health","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahelth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/ahelth.com\/es\/#\/schema\/person\/ac5d2a0af0e99e510259404003db4164","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","url":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","contentUrl":"https:\/\/ahelth.com\/wp-content\/litespeed\/avatar\/cf9c2aee656e3b593d532107b6b087d0.jpg?ver=1783820317","caption":"admin"},"sameAs":["http:\/\/ahelth.com"],"url":"https:\/\/ahelth.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts\/3759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/comments?post=3759"}],"version-history":[{"count":0,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/posts\/3759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/media\/1504"}],"wp:attachment":[{"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/media?parent=3759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/categories?post=3759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahelth.com\/it\/wp-json\/wp\/v2\/tags?post=3759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}